{"id":90631,"date":"2026-04-20T08:01:12","date_gmt":"2026-04-20T06:01:12","guid":{"rendered":"https:\/\/port.spbe.ch\/kampagne\/initiative-internet-2\/"},"modified":"2026-04-20T08:01:12","modified_gmt":"2026-04-20T06:01:12","slug":"initiative-internet-2","status":"publish","type":"cpt-campaign","link":"https:\/\/port.spbe.ch\/fr\/campagne\/initiative-internet-2\/","title":{"rendered":"Internet-Initiative"},"content":{"rendered":"","protected":false},"template":"","meta":{"open_link_in_new_window":"false"},"categories":[],"class_list":["post-90631","cpt-campaign","type-cpt-campaign","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign\/90631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign"}],"about":[{"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/types\/cpt-campaign"}],"version-history":[{"count":0,"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign\/90631\/revisions"}],"wp:attachment":[{"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/media?parent=90631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/port.spbe.ch\/fr\/wp-json\/wp\/v2\/categories?post=90631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}